{"id":458,"date":"2012-10-24T08:30:09","date_gmt":"2012-10-24T06:30:09","guid":{"rendered":"http:\/\/anjalorenz.wordpress.com\/?p=458"},"modified":"2015-08-15T23:54:27","modified_gmt":"2015-08-15T21:54:27","slug":"ecil12","status":"publish","type":"post","link":"https:\/\/secret-cow-level.de\/wordpress\/2012\/10\/ecil12\/","title":{"rendered":"Educamp Ilmenau #ecil12"},"content":{"rendered":"<div style=\"width: 801px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/plus.google.com\/u\/0\/photos\/101889696578499789127\/albums\/5802187427277622433\/5802612877854267010\"><img loading=\"lazy\" decoding=\"async\" title=\"Tafelutopie\" alt=\"\" src=\"https:\/\/lh4.googleusercontent.com\/-8QKUN-ULm3c\/UIcFqzmcVoI\/AAAAAAAAFr4\/OcxsOI6yPaw\/s791\/IMG_20121021_112133_Sophia_Metal_Grunge.jpg\" height=\"593\" width=\"791\" \/><\/a><p class=\"wp-caption-text\">Ich mag dieses Bild. Es ist bei der Session von <a href=\"http:\/\/www.twitter.com\/fraufridur\">@FrauFridur<\/a> zur Bildungsutopie entstanden und zeigt dabei so viele Aspekte des EduCamps.<\/p><\/div>\n<p style=\"text-align:left;\">Nach den EduCamps in <a title=\"Educamp Bremen\u00a0#echb11\" href=\"http:\/\/anjalorenz.wordpress.com\/2011\/03\/23\/educamp-bremen-echb11\/\">Bremen<\/a> und <a title=\"Open hei\u00dft nicht kostenlos!? \u00dcberlegungen nach dem\u00a0#ecco12\" href=\"http:\/\/anjalorenz.wordpress.com\/2012\/03\/20\/open-heist-nicht-kostenlos-uberlegungen-nach-dem-ecco12\/\">K\u00f6ln<\/a> war das <a title=\"zur Webseite\" href=\"http:\/\/educamp.mixxt.de\/\">10. EduCamp in Ilmenau<\/a> also mein drittes EduCamp \u2013 und dabei das erste, das ich nur zum &#8222;Selbstzweck&#8220; besucht habe (die anderen beiden konnte ich mit der <a title=\"zur Konferenzseite\" href=\"http:\/\/www.londonmobilelearning.net\/#bremen.php\">MLCB11<\/a> bzw. der <a title=\"zur Konferenzseite\" href=\"http:\/\/dgi-info.informationsassistent.de\/index.php\/dgi-eigenveranstaltungen\/dgi-konferenz\/dgi-konferenz-2012\">DGI12<\/a> verbinden). Ich geh\u00f6re also nicht zu den &#8222;alten Hasen&#8220;, bin aber auch kein Newbie mehr und durchaus mit den Regeln des EduCamp-Prinzips vertraut (<a title=\"zum Blog\" href=\"http:\/\/www.dotcomblog.de\/?p=3407\">@gibro<\/a> und <a title=\"zum Blog\" href=\"http:\/\/joerg-lohrer.de\/2012\/10\/23\/educamp-willkommen-im-fight-club\/\">@empeiria<\/a> haben in ihren Blogs noch einmal daran erinnert). Ich hatte im Vorfeld ein paar Sessions <a title=\"zum Forum\" href=\"http:\/\/educamp.mixxt.de\/networks\/forum\/category.59253\">im Forum<\/a> vorgeschlagen, mit- und andiskutiert, wollte mir aber bewusst sehr kurzfristig \u00fcberlegen, ob und was ich dann tats\u00e4chlich anbieten soll. Denn das ist einer der Punkte an einem EduCamp, den ich besonders sch\u00e4tze: die M\u00f6glichkeit, (subjektiv) aktuelle Themen vorzuschlagen und in einer stark interdisziplin\u00e4ren Community diskutieren zu k\u00f6nnen.<\/p>\n<div class=\"embed-privacy-container is-disabled embed-x\" data-embed-id=\"oembed_eed564eda1f885ff03d70c3dd9bba6b8\" data-embed-provider=\"x\">\t\t\t\t\t\t<button type=\"button\" class=\"embed-privacy-enable screen-reader-text\">Inhalt von X anzeigen<\/button>\t\t\t\t\t\t<\/p>\n<div class=\"embed-privacy-overlay\">\n<div class=\"embed-privacy-inner\">\n<div class=\"embed-privacy-logo\" style=\"background-image: url(https:\/\/secret-cow-level.de\/wordpress\/wp-content\/plugins\/embed-privacy\/assets\/images\/embed-x.png?ver=1.12.3);\"><\/div>\n<p>\t\tHier klicken, um den Inhalt von X anzuzeigen.\t\t\t\t\t<br \/>\t\t\t\t\tErfahre mehr in der <a href=\"https:\/\/x.com\/de\/privacy\" target=\"_blank\">Datenschutzerkl\u00e4rung von X<\/a>.\t\t<\/p>\n<p class=\"embed-privacy-input-wrapper\">\t\t\t<input id=\"embed-privacy-store-x-eed564eda1f885ff03d70c3dd9bba6b8\" type=\"checkbox\" value=\"1\" class=\"embed-privacy-input\" data-embed-provider=\"x\">\t\t\t<label for=\"embed-privacy-store-x-eed564eda1f885ff03d70c3dd9bba6b8\" class=\"embed-privacy-label\" data-embed-provider=\"x\">\t\t\t\tInhalt von X immer anzeigen\t\t\t<\/label>\t\t<\/p>\n<\/p><\/div>\n<div class=\"embed-privacy-footer\"><span class=\"embed-privacy-url\"><a href=\"https:\/\/twitter.com\/anjalorenz\/status\/259217484199104513\">Tweet direkt \u00f6ffnen<\/a><\/span><\/div>\n<\/p><\/div>\n<div class=\"embed-privacy-content\">\t\t\t\t<script>var _oembed_eed564eda1f885ff03d70c3dd9bba6b8 = '{\\\"embed\\\":\\\"&lt;blockquote class=&quot;twitter-tweet&quot; data-width=&quot;550&quot; data-dnt=&quot;true&quot;&gt;&lt;p lang=&quot;de&quot; dir=&quot;ltr&quot;&gt;Gerade nachgeschaut: &lt;a href=&quot;https:\\\\\/\\\\\/twitter.com\\\\\/hashtag\\\\\/Ilmenau?src=hash&amp;amp;ref_src=twsrc%5Etfw&quot;&gt;#Ilmenau&lt;\\\\\/a&gt; ist sogar noch kleiner als &lt;a href=&quot;https:\\\\\/\\\\\/twitter.com\\\\\/hashtag\\\\\/Zeitz?src=hash&amp;amp;ref_src=twsrc%5Etfw&quot;&gt;#Zeitz&lt;\\\\\/a&gt; &lt;a href=&quot;https:\\\\\/\\\\\/twitter.com\\\\\/hashtag\\\\\/ecil12?src=hash&amp;amp;ref_src=twsrc%5Etfw&quot;&gt;#ecil12&lt;\\\\\/a&gt;. Da f&uuml;hle ich mich bestimmt schnell zu Hause.&lt;\\\\\/p&gt;&amp;mdash; Anja Lorenz (@anjalorenz) &lt;a href=&quot;https:\\\\\/\\\\\/twitter.com\\\\\/anjalorenz\\\\\/status\\\\\/259217484199104513?ref_src=twsrc%5Etfw&quot;&gt;October 19, 2012&lt;\\\\\/a&gt;&lt;\\\\\/blockquote&gt;&lt;script async src=&quot;https:\\\\\/\\\\\/platform.twitter.com\\\\\/widgets.js&quot; charset=&quot;utf-8&quot;&gt;&lt;\\\\\/script&gt;\\\"}';<\/script>\t\t\t<\/div>\n<\/p><\/div>\n<p>Mir ist der Th\u00fcringer Wald eigentlich sehr gut bekannt (jahrelang haben wir Silvester in Suhl verbracht und kennen auch Oberhof, Sonneberg, Meiningen, Ohrdruff, Lauscha, Gotha u.v.m.), nach Ilmenau hatte es uns aber noch nicht verschlagen. Aber es ist sehr sch\u00f6n hier und das bei diesem Wetter: 25\u00b0C im Oktober! Ilmenau war Ausrichter des <a title=\"zur Webseite\" href=\"http:\/\/educamp.mixxt.de\/networks\/wiki\/index.archiv-ec08-1\">ersten<\/a> und <a title=\"zur Webseite\" href=\"http:\/\/educamp.mixxt.de\/networks\/wiki\/index.archiv-ec09-3\">dritten<\/a> EduCamps, die ich aber zum Vergleich nicht heranziehen kann (ist also nur f\u00fcr die Statistik). Die Ausrichtung in einer Uni hat schonmal einen Vorteil: Es gibt Eduroam, f\u00fcr die quasi \u00fcberlebenswichtige WLAN-Verbindung ist also gesorgt. Ebenso waren alle R\u00e4ume mit Beamer und Tafel ausgestattet. Die Infrastruktur zusammen mit der tollen Orga und den Helfern bot ein ideales Umfeld f\u00fcr das EduCamp.<\/p>\n<p>Die Beschreibung der Sessions ist mir jetzt irgendwie ausgeartet, die kommt noch einmal <a title=\"zum Blog-Beitrag\" href=\"http:\/\/wp.me\/p14spe-8H\">hier<\/a>.<\/p>\n<h2>Na dann geht es los: 5-Finger-Feedback!<\/h2>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"Daumen: Das war super!\" alt=\"\" src=\"https:\/\/lh5.googleusercontent.com\/-w7lWFy9jc-k\/T-r2V2AA5yI\/AAAAAAAAC3Q\/SaPK9frt3y8\/s807\/IMG_20120607_152213.jpg\" width=\"200\" \/><\/p>\n<p><strong>Daumen: Das wa super! <\/strong>Das Organisationsteam und vor allem die vielen Helfer waren unschlagbar: Egal wie oft man doch noch mal an seine Tasche musste oder ob man Hilfe bei der Raumtechnik brauchte: die vermutlich \u00fcberwiegend Studenten waren immer freundlich, locker und hilfsbereit und es war auch immer etwas Zeit, sich pers\u00f6nlich noch einmal auszutauschen. Die Themen waren aus meiner Perspektive abwechslungsreich und ich hatte oft auch Probleme, mich f\u00fcr eine Session zu entscheiden.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"Zeigefinger: Das k\u00f6nnte man besser machen!\" alt=\"\" src=\"https:\/\/lh5.googleusercontent.com\/-tNRiE-xXcZQ\/T-r2eZC-AuI\/AAAAAAAAC3Y\/tMJTa9POWpc\/s807\/IMG_20120607_152219.jpg\" width=\"200\" \/><\/p>\n<p><strong>Zeigefinger: Das k\u00f6nnte man besser machen!<\/strong> Nun folgt &#8222;Meckern auf hohem Niveau&#8220;. Das Quiz am Freitag war gut und f\u00fcr Nicht-Kneipenquiz&#8217;ler war es sicher auch schwer genug. Sollte man sowas wiederholen wollen (und f\u00fcr eine spielerische Quizzerei w\u00e4re ich auf alle F\u00e4lle) kann man sich bspw. mal an Bildungsthemen oder st\u00e4rker noch \u00f6rtliche Gegebenheiten herantrauen. Am Sonntag fehlte die Vorstellungsrunde und auch die Newbie-Begleitung schien nicht vorhanden bzw. nur individuell organisiert gewesen zu sein. Ja klar, ich habe es damals auch ohne geschafft, aber ich fand das Angebot in K\u00f6ln (?) sehr gut und w\u00fcrde mich gern da auch selbst einbringen (ich brauche aber vermutlich vor dem #echh13 eine Erinnerung).<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"Mittelfinger: Das hat mir gar nicht gefallen!\" alt=\"\" src=\"https:\/\/lh3.googleusercontent.com\/-rMuqg-7kX9s\/T-r2l9gc1cI\/AAAAAAAAC3g\/5Dht3IEUBvo\/s807\/IMG_20120607_152223.jpg\" width=\"200\" \/><\/p>\n<p><strong>Mittelfinger: Das hat mir gar nicht gefallen!<\/strong> Eigentlich m\u00f6chte ich gar nicht mehr so viel dazu sagen, hier wird an anderer Stelle genug diskutiert. Vielleicht allgemein: Diskussionen sollten zu jedem Zeitpunkt konstruktiv gef\u00fchrt werden. So wie das bei <a title=\"zum Twitter-Account\" href=\"https:\/\/twitter.com\/jmm_hamburg\">@jmm_hamburg<\/a> gelaufen ist: es hat ihn etwas gest\u00f6rt und das ganze war dann Anlass zu einer <a title=\"zum Video\" href=\"http:\/\/www.youtube.com\/watch?v=YjEj6LkPizg\">Session<\/a>. Ohne b\u00f6ses Blut, aber um dennoch darauf hinzuweisen. Und ich kann nur noch einmal betonen: Ich f\u00e4nde einen <a title=\"zur Forendiskussion\" href=\"http:\/\/educamp.mixxt.de\/networks\/forum\/thread.241904\">Crowdfunding-Versuch<\/a> gut und interessant, sehe aber auch Gefahren, dass es nicht klappen k\u00f6nnte. Einfach hinschmei\u00dfen erspart diese Herausforderung.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"Ringfinger: Das nehme ich mit!\" alt=\"\" src=\"https:\/\/lh6.googleusercontent.com\/-VJaaqdO3_Bc\/T-r2sOo-b0I\/AAAAAAAAC3o\/ZgT_FNmHDoc\/s807\/IMG_20120607_152230.jpg\" width=\"200\" \/><\/p>\n<p><strong>Ringfinger: Das nehme ich mit!<\/strong> Ich werde <a title=\"zur Webseite\" href=\"http:\/\/sketchnotes.de\/\">Sketchnotes<\/a> weiter verfolgen und wo es geht ausprobieren. Ich werde die <a title=\"zum Video\" href=\"http:\/\/www.youtube.com\/watch?v=U-mqZ_KD1Lo\">Akademie 2.0<\/a> soweit es geht verfolgen, ich bin gespannt, wie sich dieses Projekt weiterentwickelt. Ich werden versuchen, am <a title=\"zum Video\" href=\"http:\/\/www.youtube.com\/watch?v=244PEtc5at8\">L3T 2.0<\/a> mitzuwirken. Ich werde das <a title=\"zur Webseite\" href=\"http:\/\/wiki.zum.de\/Hauptseite\">ZUM-Wiki <\/a>und die <a title=\"zur Webseite\" href=\"http:\/\/de.wikiversity.org\/wiki\/Hauptseite\">WikiVersity<\/a> erw\u00e4hnen, wo ich kann. Ich werde die<a title=\"zum Blog-Beitrag\" href=\"http:\/\/freuleinfridur.wordpress.com\/2012\/10\/22\/ecil12-bildungsutopia-basteln-session\/\"> Bildungsutopie<\/a> nicht aus den Augen verlieren. Ich werde weiterhin schauen, dass ich andere beim UrhG-konformen Einsatz von Medien helfen kann. Ich werde es hoffentlich schaffen, das BarCamp-Format mal im <a title=\"zur Webseite\" href=\"http:\/\/chembows.de\/\">Verein<\/a> zu testen. Ich werde die Kontakte aus dem EduCamp halten. Ich werde (hoffentlich) zum <a title=\"zum Twitter-Account\" href=\"https:\/\/twitter.com\/echh13\">@echh13<\/a> kommen.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" title=\"Kleiner Finger: Das ist mir zu kurz gekommen!\" alt=\"\" src=\"https:\/\/lh6.googleusercontent.com\/-qXozEaQe72k\/T-r20aLrHyI\/AAAAAAAAC3w\/kBPkd1LNSq8\/s807\/IMG_20120607_152234.jpg\" width=\"200\" \/><\/p>\n<p><strong>Kleiner Finger: Das ist mir zu kurzgekommen!<\/strong> Bei 30 Sessions h\u00e4tte ich einige Sessions gern auch noch besucht. Und nat\u00fcrlich h\u00e4tte ich auch von Ilmenau gern mehr gesehen. Aber ich kann mich nunmal nicht verteilen. Sicher konnte ich auch nicht mit jedem in dem Umfang sprechen, wie ich es mir gew\u00fcnscht h\u00e4tte. <a title=\"zum Blog-Beitrag\" href=\"http:\/\/birgit-rydlewski.de\/2012\/10\/20\/educamp-und-weiter\/\">In anderen Blogs<\/a> wird der politische Impact des EduCamps thematisiert, aber da sehe ich das anders: Das EduCamp ist keine politische Veranstaltung und soll keine werden. Es geht nicht darum, Meinungen und Haltungen zu diskutieren, es geht auch nicht um richtig und falsch. Es geht um einen Rahmen, in dem\u00a0 ungezwungen von disziplin\u00e4ren Schranken und konkreten Zielen ein Austausch stattfinden kann. Ohne Vorgaben, ohne n\u00f6tige Themen, ohne Gewinner und Verlierer, ohne Regierung und Opposition.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach den EduCamps in Bremen und K\u00f6ln war das 10. EduCamp in Ilmenau also mein drittes EduCamp \u2013 und dabei das erste, das ich nur zum &#8222;Selbstzweck&#8220; besucht habe (die anderen beiden konnte ich mit der MLCB11 bzw. der DGI12&#8230; <a class=\"more-link\" href=\"https:\/\/secret-cow-level.de\/wordpress\/2012\/10\/ecil12\/\">Weiterlesen &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_metis_text_type":"standard","_metis_text_length":5330,"_post_count":0,"footnotes":""},"categories":[26,28],"tags":[72,73,94,109,117,136,182],"class_list":["post-458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educamps","category-l3t","tag-ecil12","tag-educamp","tag-ilmenau","tag-l3t","tag-learning","tag-notes","tag-teaching"],"public_identification_id":"6c79330d19fd484f9bc4733ee05619ee","private_identification_id":"426e9888d60d4afeb5de9d981dcefc5f","_links":{"self":[{"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/posts\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":1,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/posts\/458\/revisions"}],"predecessor-version":[{"id":1846,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/posts\/458\/revisions\/1846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/media\/1845"}],"wp:attachment":[{"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/media?parent=458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/categories?post=458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/secret-cow-level.de\/wordpress\/wp-json\/wp\/v2\/tags?post=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}